

{"id":10984,"date":"2014-06-03T17:59:28","date_gmt":"2014-06-03T15:59:28","guid":{"rendered":"https:\/\/ufmsecretariat.org\/?p=10984"},"modified":"2014-08-04T12:56:00","modified_gmt":"2014-08-04T10:56:00","slug":"du-developpement-urbain-au-soutien-aux-pme-quatre-nouveaux-projets-labellises-par-lunion-pour-la-mediterranee","status":"publish","type":"post","link":"https:\/\/ufmsecretariat.org\/fr\/du-developpement-urbain-au-soutien-aux-pme-quatre-nouveaux-projets-labellises-par-lunion-pour-la-mediterranee\/","title":{"rendered":"Du d\u00e9veloppement urbain au soutien aux PME : quatre nouveaux projets labellis\u00e9s par l\u2019Union pour la M\u00e9diterran\u00e9e"},"content":{"rendered":"<p style=\"text-align: justify;\"><b>Barcelone, le 3 juin 2014. <\/b>Lors de la derni\u00e8re r\u00e9union des hauts fonctionnaires qui s\u2019est tenue \u00e0 Bruxelles les 2 et 3 juin, les hauts fonctionnaires des 43 \u00c9tats membres de l\u2019UpM ont approuv\u00e9 l\u2019adoption de quatre projets importants\u00a0:<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/ufmsecretariat.org\/\/fr\/promoting-financial-inclusion-via-mobile-financial-services-in-the-southern-and-eastern-mediterranean-countries\/\" target=\"_blank\"><b>Finances mobiles \u2013 Promotion de l\u2019inclusion financi\u00e8re \u00e0 travers de services financiers mobiles aux pays du Sud et de l\u2019Est de la M\u00e9diterran\u00e9e. <\/b><\/a>Promu par les banques centrales du Maroc et de la Jordanie et devant \u00eatre mis en \u0153uvre par la Banque europ\u00e9enne d\u2019investissement, ce projet vise \u00e0 \u00e9largir l\u2019acc\u00e8s aux services financiers au sein de la population de la r\u00e9gion m\u00e9diterran\u00e9enne \u00e0 travers le d\u00e9veloppement de solutions de paiement de masse novatrices telles que les services financiers mobiles. Les autorit\u00e9s de r\u00e9glementation financi\u00e8re dans la r\u00e9gion \u00e9tudient actuellement comment les services financiers mobiles peuvent \u00eatre utilis\u00e9s en vue d\u2019\u00e9tendre l\u2019acc\u00e8s aux services financiers tout en maintenant la stabilit\u00e9 du syst\u00e8me financier. \u00c0 cet \u00e9gard, le projet fournira un ensemble complet d\u2019assistance technique et d\u2019actions de renforcement des capacit\u00e9s, adapt\u00e9 aux sp\u00e9cificit\u00e9s de chaque pays.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/ufmsecretariat.org\/\/fr\/projet-de-renovation-urbaine-dimbaba\/\" target=\"_blank\"><b>Projet de r\u00e9novation urbaine d\u2019Imbaba<\/b><\/a><b>. <\/b>Ce projet s\u2019appuie sur les efforts actuels du gouvernorat de Gizeh en vue de transformer un ancien a\u00e9roport d\u2019Imbaba en un centre urbain dynamique comprenant un important parc public, un complexe r\u00e9sidentiel, des centres commerciaux et de nouvelles routes visant \u00e0 am\u00e9liorer l\u2019accessibilit\u00e9 de la zone. Le projet vise ainsi \u00e0 renforcer l\u2019int\u00e9gration d\u2019Imbaba au sein de l\u2019ensemble de la ville du Caire et \u00e0 fournir \u00e0 700\u00a0000 habitants les services et infrastructures de base n\u00e9cessaires (installations m\u00e9dicales, \u00e9coles, parcs de loisirs, \u00e9quipements sportifs, etc.). Le projet fait partie des projets s\u00e9lectionn\u00e9s par l\u2019<a href=\"https:\/\/ufmsecretariat.org\/\/fr\/the-euro-mediterranean-sustainable-urban-strategy-is-on-its-way-2\/\" target=\"_blank\">Initiative pour le financement de projets urbains (UPFI)<\/a>. UPFI vise \u00e0 promouvoir et d\u00e9velopper des projets urbains durables et innovants qui servent d\u2019exemples des meilleures pratiques et qui peuvent \u00eatre r\u00e9utilis\u00e9s. L\u2019initiative est g\u00e9r\u00e9e par l\u2019Agence Fran\u00e7aise de D\u00e9veloppement (AFD) et la Banque d\u2019Investissement Europ\u00e9enne (BEI) en liaison avec le Commission Europ\u00e9enne (CE) et dans le cadre du Secr\u00e9tariat de l\u2019UpM. La banque Allemagne KFW, la Caisse des D\u00e9p\u00f4ts fran\u00e7aise (CDC) et la Banque Europ\u00e9enne pour la Reconstruction et le D\u00e9veloppement (BERD) sont aussi associ\u00e9es. D\u2019autres IFIs et investisseurs comme la Banque Africaine de D\u00e9veloppement (AFD) et La Caixa ont montr\u00e9 leur int\u00e9r\u00eat.<\/p>\n<p><a href=\"https:\/\/ufmsecretariat.org\/\/fr\/establishment-of-a-regional-platform-for-the-development-of-cultural-and-creative-industries-and-clusters-in-the-southern-mediterranean\/\" target=\"_blank\"><b>\u00c9tablissement d\u2019une plateforme r\u00e9gionale pour le D\u00e9veloppement de Clusters dans les Industries Culturelles et Cr\u00e9atives de la R\u00e9gion Sud<\/b><\/a><b><a href=\"https:\/\/ufmsecretariat.org\/\/fr\/establishment-of-a-regional-platform-for-the-development-of-cultural-and-creative-industries-and-clusters-in-the-southern-mediterranean\/\" target=\"_blank\"> de la M\u00e9diterran\u00e9e<\/a>.\u00a0<\/b>Promu par l\u2019Organisation des Nations Unies pour le d\u00e9veloppement industriel (ONUDI), ce projet vise \u00e0 favoriser la coop\u00e9ration entre entreprises, \u00e0 exploiter le potentiel des industries culturelles et cr\u00e9atives et \u00e0 cr\u00e9er de nouvelles possibilit\u00e9s d\u2019emplois et favoriser la croissance inclusive au sud de la r\u00e9gion\u00a0m\u00e9diterran\u00e9enne. Le projet fournira une plateforme de dialogue et d\u2019\u00e9change de bonnes pratiques concernant les politiques dans le secteur culturel et cr\u00e9atif. Les b\u00e9n\u00e9ficiaires de ce projet sont les micro, petites et moyennes entreprises qui font partie des p\u00f4les pilotes soutenus par le biais de l\u2019initiative du EU-ONUDI \u00ab\u00a0P\u00f4les d\u2019industries culturelles et cr\u00e9atives dans le sud de la r\u00e9gion m\u00e9diterran\u00e9enne\u00a0\u00bb, ainsi que des institutions gouvernementales r\u00e9gionales et nationales, qui b\u00e9n\u00e9ficieront de l\u2019exp\u00e9rience d\u2019apprentissage li\u00e9e au projet et acquerront des connaissances sur les m\u00e9thodologies de d\u00e9veloppement de p\u00f4les. Le projet s\u2019inscrit dans le cadre du deuxi\u00e8me axe de l\u2019<a href=\"https:\/\/ufmsecretariat.org\/\/fr\/mediterranean-initiative-for-jobs-med4jobs\/\" target=\"_blank\">Initiative M\u00e9diterran\u00e9enne pour l\u2019Emploi (Med4jobs)<\/a>\u00a0: le d\u00e9veloppement du secteur priv\u00e9 et de la croissance inclusive.<\/p>\n<p style=\"text-align: justify;\"><b><a href=\"https:\/\/ufmsecretariat.org\/\/fr\/bluegreen-med-cs\/\" target=\"_blank\">BlueGreen Med-CS<\/a>.<\/b><b> <\/b>Promu par le Centre de coop\u00e9ration pour la M\u00e9diterran\u00e9e (UICN-Med), l\u2019Institut M\u00e9diterran\u00e9en de l\u2019Eau (IME), le Bureau m\u00e9diterran\u00e9en d\u2019information sur l\u2019environnement, la culture et le d\u00e9veloppement durable (MIO-ESCDE), le R\u00e9seau arabe pour l\u2019environnement et le d\u00e9veloppement (RAED) et le WWF Mediterranean Programme Office (WWF-MedPO), le projet vise \u00e0 saisir les opportunit\u00e9s financi\u00e8res et de coop\u00e9ration existantes \u2013 et \u00e0 en cr\u00e9er de nouvelles &#8211; au sein des organisations de la soci\u00e9t\u00e9 civile (OSC) dans le domaine de l\u2019eau et de l\u2019environnement.<\/p>\n<p style=\"text-align: justify;\">Le projet permettra de lancer un programme de renforcement des capacit\u00e9s et un syst\u00e8me de petites subventions pour les ONG afin qu\u2019elles acqui\u00e8rent des comp\u00e9tences dans diff\u00e9rents domaines li\u00e9s au d\u00e9veloppement durable, notamment sur les zones humides, la gestion de la demande en eau, l\u2019utilisation efficiente de l\u2019eau, la gestion transfrontali\u00e8re des ressources en eau, l\u2019\u00e9ducation et la sensibilisation \u00e0 l\u2019environnement ainsi que sur la question des d\u00e9chets marins. Les activit\u00e9s contribueront au renforcement du dialogue entre les OSC m\u00e9diterran\u00e9ennes s\u00e9lectionn\u00e9es et les autorit\u00e9s nationales.<\/p>\n<p style=\"text-align: justify;\">Le Secr\u00e9tariat de l\u2019Union pour la M\u00e9diterran\u00e9e continuera de superviser le d\u00e9veloppement, la mise en \u0153uvre et le suivi des projets r\u00e9gionaux visant \u00e0 renforcer la coop\u00e9ration r\u00e9gionale au sein de la r\u00e9gion m\u00e9diterran\u00e9enne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quatre projets favorisant le financement mobile, le d\u00e9veloppement urbain durable, la coop\u00e9ration entre des organisations de la soci\u00e9t\u00e9 civile \u0153uvrant dans le domaine de l\u2019eau et de l\u2019environnement ainsi que le d\u00e9veloppement du secteur priv\u00e9 ont \u00e9t\u00e9 approuv\u00e9s par les 43 \u00c9tats membres de l\u2019Union pour la M\u00e9diterran\u00e9e (UpM).<\/p>\n","protected":false},"author":3,"featured_media":10980,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92,85,76,84],"tags":[],"priority-area":[193],"class_list":["post-10984","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-actualites-phares","category-developpement-des-entreprises","category-transport-et-developpement-urbain","priority-area-business-development-fr"],"_links":{"self":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/10984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/comments?post=10984"}],"version-history":[{"count":7,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/10984\/revisions"}],"predecessor-version":[{"id":10989,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/10984\/revisions\/10989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/media\/10980"}],"wp:attachment":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/media?parent=10984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/categories?post=10984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/tags?post=10984"},{"taxonomy":"priority-area","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/priority-area?post=10984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}