

{"id":136867,"date":"2022-06-27T13:51:11","date_gmt":"2022-06-27T12:51:11","guid":{"rendered":"https:\/\/ufmsecretariat.org\/\/?p=136867"},"modified":"2022-06-27T14:14:26","modified_gmt":"2022-06-27T13:14:26","slug":"ministerial-conference-research-innovation-2022","status":"publish","type":"post","link":"https:\/\/ufmsecretariat.org\/fr\/ministerial-conference-research-innovation-2022\/","title":{"rendered":"Les Ministres de l&#8217;UpM lancent un nouvel agenda pour la recherche et l&#8217;innovation pour la r\u00e9gion euro-m\u00e9diterran\u00e9enne"},"content":{"rendered":"<ul class=\"ul1\">\n<li class=\"li1\"><b>Les Ministres de la Recherche et de l&#8217;Innovation des 42 pays de l&#8217;Union pour la M\u00e9diterran\u00e9e (UpM) se sont r\u00e9unis pour la premi\u00e8re fois pour discuter des moyens de promouvoir la coop\u00e9ration scientifique sur le changement climatique, les \u00e9nergies renouvelables et la sant\u00e9.<\/b><\/li>\n<li class=\"li1\"><b>Ils ont approuv\u00e9 une d\u00e9claration minist\u00e9rielle qui vise \u00e0 exploiter le potentiel de la recherche et de l&#8217;innovation pour accro\u00eetre la r\u00e9silience de la r\u00e9gion euro-m\u00e9diterran\u00e9enne face aux d\u00e9fis environnementaux, socio-\u00e9conomiques et de s\u00e9curit\u00e9 alimentaire, ainsi qu&#8217;\u00e0 promouvoir la diplomatie scientifique.<\/b><\/li>\n<\/ul>\n<p class=\"p1\"><b>Paris, le 27 juin 2022. <\/b>La Conf\u00e9rence minist\u00e9rielle sur la recherche et l&#8217;innovation (R&amp;I) de l&#8217;Union pour la M\u00e9diterran\u00e9e s&#8217;est tenue aujourd\u2019hui afin de promouvoir la coop\u00e9ration pour la science et la connaissance dans la r\u00e9gion. Sous la copr\u00e9sidence de l&#8217;Union europ\u00e9enne, la <b>Commissaire Mariya Gabriel<\/b> et la Jordanie, <b>la Ministre Haifaa Najjar<\/b> et en pr\u00e9sence de <b>Nasser Kamel, Secr\u00e9taire G\u00e9n\u00e9ral de l&#8217;UpM<\/b>, la conf\u00e9rence a \u00e9t\u00e9 anim\u00e9e par <b>Sylvie Retailleau, Ministre fran\u00e7aise de l&#8217;Enseignement sup\u00e9rieur et de la Recherche<\/b>, au nom de la Pr\u00e9sidence fran\u00e7aise du Conseil de l&#8217;Union europ\u00e9enne.<\/p>\n<p class=\"p1\">La conf\u00e9rence est la premi\u00e8re r\u00e9union minist\u00e9rielle sur la recherche et l&#8217;innovation de l&#8217;UpM.<\/p>\n<p class=\"p1\">Dans la perspective des d\u00e9fis actuels et futurs de la r\u00e9gion, les ministres ont adopt\u00e9 une d\u00e9claration minist\u00e9rielle qui ouvre la voie \u00e0 un approfondissement de la coop\u00e9ration scientifique, \u00e0 l\u2019am\u00e9lioration de la collaboration dans la recherche, l&#8217;innovation et de d\u00e9veloppement des comp\u00e9tences et au soutien du renforcement des capacit\u00e9s, de la coordination et des actions conjointes, notamment en mati\u00e8re de d\u00e9veloppement durable et employabilit\u00e9.<\/p>\n<p class=\"p1\">Les Ministres ont pris acte de trois nouvelles feuilles de route euro-m\u00e9diterran\u00e9enne pour la recherche et l&#8217;innovation (R&amp;I) sur le changement climatique, les \u00e9nergies renouvelables et la sant\u00e9. Elles serviront de catalyseur pour la coop\u00e9ration future. Une action rapide est n\u00e9cessaire et un plan de mise en \u0153uvre, \u00e9labor\u00e9 par la <a href=\"https:\/\/ufmsecretariat.org\/\/platform\/ufm-regional-platform-on-research-and-innovation\/\" target=\"_blank\" rel=\"noopener\"><span class=\"s1\">plate-forme r\u00e9gionale de l&#8217;UpM pour la recherche et l&#8217;innovation<\/span><\/a>, transformera ces priorit\u00e9s en actions sp\u00e9cifiques, en examinant les progr\u00e8s r\u00e9alis\u00e9s et favorisant de nouvelles synergies avec les instruments nouveaux et existants. Dans le cadre des Objectifs de d\u00e9veloppement durable des Nations Unies et son Programme 2030, la bonne mise en \u0153uvre des feuilles de route est cruciale pour obtenir les changements souhait\u00e9s dans la r\u00e9gion. Les feuilles de route impliquent les acteurs de la r\u00e9gion au sens large (ONG, institutions scientifiques, chercheurs, r\u00e9seaux d&#8217;universit\u00e9s et citoyens, secteur priv\u00e9 et d\u00e9cideurs), ainsi que les organisations internationales, les institutions financi\u00e8res et les donateurs.<\/p>\n<p class=\"p1\"><b>La Ministre fran\u00e7aise de l&#8217;Enseignement sup\u00e9rieur et de la Recherche, Sylvie Retailleau, <\/b>a d\u00e9clar\u00e9 : \u00ab Cette toute premi\u00e8re r\u00e9union des Ministres de la Recherche et de l&#8217;Innovation sous l&#8217;\u00e9gide de l&#8217;UpM arrive \u00e0 point nomm\u00e9. Aujourd&#8217;hui, nous prenons des mesures politiques importantes pour renforcer la coop\u00e9ration R&amp;I dans la r\u00e9gion euro-m\u00e9diterran\u00e9enne sur le changement climatique, les \u00e9nergies renouvelables et la sant\u00e9. C&#8217;est un message tr\u00e8s clair en faveur d&#8217;une coop\u00e9ration en R&amp;I bas\u00e9e sur des valeurs et principes fondamentaux communs afin de soutenir des soci\u00e9t\u00e9s plus r\u00e9silientes dans notre espace partag\u00e9.\u00a0\u00bb<\/p>\n<p class=\"p1\"><b>Mariya Gabriel, Commissaire charg\u00e9e de l&#8217;innovation, de la recherche, de la culture, de l&#8217;\u00e9ducation et de la jeunesse,<\/b> a d\u00e9clar\u00e9 : \u00ab Aujourd&#8217;hui, nous avons franchi une autre \u00e9tape importante dans le renforcement du partenariat strat\u00e9gique entre l&#8217;UE et ses partenaires du voisinage m\u00e9ridional, auquel nous nous sommes engag\u00e9s dans le nouvel agenda 2021 pour le M\u00e9diterran\u00e9e et dans l\u2019Approche Globale de la Recherche et de l&#8217;Innovation. Une chose est claire. L&#8217;avenir, c&#8217;est de travailler ensemble, de se rapprocher et de trouver des solutions innovantes aux d\u00e9fis communs du climat, de l&#8217;\u00e9nergie et de la sant\u00e9. Ceci est et continuera d&#8217;\u00eatre au c\u0153ur de notre partenariat et soutenu par Horizon Europe pour r\u00e9pondre aux trois feuilles de route de la recherche et de l&#8217;innovation \u00bb.<\/p>\n<p class=\"p1\">La <b>Ministre par int\u00e9rim de l&#8217;Enseignement sup\u00e9rieur et de la Recherche scientifique du Royaume hach\u00e9mite de Jordanie, Haifaa Najjar<\/b>, a d\u00e9clar\u00e9 : \u00ab Une action opportune est n\u00e9cessaire pour exploiter les avantages de la coop\u00e9ration en mati\u00e8re de recherche et d&#8217;innovation dans la r\u00e9gion m\u00e9diterran\u00e9enne et entreprendre des r\u00e9formes ambitieuses pour maintenir nos ressources et assurer la stabilit\u00e9 et croissance \u00e9conomique. Je crois que la nouvelle d\u00e9claration sur la recherche et l&#8217;innovation soutiendra les efforts et les besoins de nos communaut\u00e9s dans la poursuite d&#8217;une coop\u00e9ration efficace \u00bb.<\/p>\n<p class=\"p1\">Le <b>Secr\u00e9taire G\u00e9n\u00e9ral de l&#8217;UpM, Nasser Kamel, a d\u00e9clar\u00e9<\/b> : \u00ab L&#8217;ampleur des d\u00e9fis mondiaux actuels et leur impact sur notre fragile \u00e9cosyst\u00e8me r\u00e9gional nous appellent \u00e0 puiser dans le potentiel de la recherche et de l&#8217;innovation pour trouver de nouvelles solutions \u00e0 la crise climatique et transformer nos syst\u00e8mes \u00e9nerg\u00e9tiques et de sant\u00e9. L&#8217;UpM a toujours promu un agenda positif pour la coop\u00e9ration scientifique, ce qui est clairement d\u00e9montr\u00e9 par la D\u00e9claration et les feuilles de route sur la recherche et l&#8217;innovation approuv\u00e9es aujourd&#8217;hui par tous les \u00c9tats membres.\u00a0\u00bb<\/p>\n<p class=\"p1\">La Conf\u00e9rence minist\u00e9rielle a pass\u00e9 en revue les progr\u00e8s r\u00e9alis\u00e9s dans la coop\u00e9ration r\u00e9gionale en mati\u00e8re de recherche et d&#8217;innovation depuis la D\u00e9claration euro-m\u00e9diterran\u00e9enne de La Valette sur le \u00ab\u00a0Renforcement de la coop\u00e9ration euro-m\u00e9diterran\u00e9enne par la recherche et l&#8217;innovation\u00a0\u00bb, publi\u00e9e en 2017. \u00c0 cette \u00e9poque, un accord a \u00e9t\u00e9 conclu pour donner la priorit\u00e9 \u00e0 la coop\u00e9ration sur la croissance bleue et l&#8217;emploi par le biais de l&#8217;initiative BLUEMED, qui vise \u00e0 lutter contre la pollution pour une mer M\u00e9diterran\u00e9e et des r\u00e9gions c\u00f4ti\u00e8res saines, productives et r\u00e9silientes. L\u2019accord soulignait \u00e9galement le Partenariat pour la recherche et l&#8217;innovation dans l&#8217;espace m\u00e9diterran\u00e9en (PRIMA), qui vise \u00e0 parvenir \u00e0 une gestion durable des ressources en eau, des syst\u00e8mes agricoles et des cha\u00eenes de valeur agro-alimentaires, et sa recherche sur les liens et la migration, et qui a abouti \u00e0 un certain nombre de projets de collaborations de recherche, financ\u00e9s par le programme-cadre de l&#8217;UE.<\/p>\n<p class=\"p1\">Lors de la r\u00e9union minist\u00e9rielle de 2022, les valeurs et principes fondamentaux communs de la coop\u00e9ration en mati\u00e8re de recherche et de diplomatie scientifique ont \u00e9t\u00e9 reconnus, ainsi que la n\u00e9cessit\u00e9 d&#8217;uniformiser les r\u00e8gles du jeu et de collaborer sur l&#8217;ouverture de la science et des donn\u00e9es.<\/p>\n<p class=\"p1\"><b>Plus d&#8217;information<\/b><\/p>\n<p class=\"p1\">Le dialogue r\u00e9gional sur la recherche et l&#8217;innovation dans la r\u00e9gion euro-m\u00e9diterran\u00e9enne a \u00e9t\u00e9 int\u00e9gr\u00e9 dans le cadre de l&#8217;UpM en 2020. La <a href=\"https:\/\/ufmsecretariat.org\/\/wp-content\/uploads\/2022\/06\/UfM-RI-Ministerial-Declaration_FR-with-logo.pdf\" target=\"_blank\" rel=\"noopener\">d\u00e9claration<\/a> minist\u00e9rielle est le r\u00e9sultat d&#8217;un processus de n\u00e9gociation entre les 42 \u00c9tats membres de l&#8217;UpM.<\/p>\n<p class=\"p1\"><b>Exemples d&#8217;initiatives et de projets en cours<\/b><\/p>\n<p class=\"p2\"><span class=\"s2\"><a href=\"https:\/\/ec.europa.eu\/info\/research-and-innovation\/funding\/funding-opportunities\/funding-programmes-and-open-calls\/horizon-europe_en\" target=\"_blank\" rel=\"noopener\">Horizon Europe<\/a><\/span><\/p>\n<p class=\"p1\">Horizon Europe est le programme de financement de la recherche et de l&#8217;innovation de l&#8217;UE dot\u00e9 d&#8217;un budget de 95,5 milliards d&#8217;euros. Il lutte contre le changement climatique, contribue \u00e0 la r\u00e9alisation des objectifs de d\u00e9veloppement durable des Nations unies et stimule la comp\u00e9titivit\u00e9 et la croissance de l&#8217;UE. Le programme facilite la collaboration et renforce l&#8217;impact de la recherche et de l&#8217;innovation dans le d\u00e9veloppement, le soutien et la mise en \u0153uvre des politiques de l&#8217;UE tout en relevant les d\u00e9fis mondiaux. Il soutient la cr\u00e9ation et une meilleure diffusion d&#8217;excellentes connaissances et technologies. Il cr\u00e9e des emplois, mobilise pleinement le vivier de talents de l&#8217;UE, stimule la croissance \u00e9conomique, favorise la comp\u00e9titivit\u00e9 industrielle et optimise l&#8217;impact des investissements au sein d&#8217;un espace europ\u00e9en de la recherche renforc\u00e9.<\/p>\n<p class=\"p2\"><span class=\"s2\"><a href=\"https:\/\/prima-med.org\/\" target=\"_blank\" rel=\"noopener\">PRIMA &#8211; partenariat pour la recherche et l\u2019innovation en M\u00e9diterran\u00e9e<span class=\"Apple-converted-space\">\u00a0<\/span><\/a><\/span><\/p>\n<p class=\"p1\">PRIMA \u2013 Partenariat pour la Recherche et l&#8217;Innovation en M\u00e9diterran\u00e9e est un programme conjoint entrepris dans le cadre de la coop\u00e9ration euro-m\u00e9diterran\u00e9enne. En finan\u00e7ant la R&amp;I par le biais d&#8217;appels comp\u00e9titifs, PRIMA se concentre sur le renforcement des capacit\u00e9s de recherche et d&#8217;innovation et le d\u00e9veloppement de connaissances et de solutions innovantes communes pour les syst\u00e8mes agroalimentaires, pour les rendre durables, et pour l&#8217;approvisionnement et la gestion int\u00e9gr\u00e9s de l&#8217;eau dans la r\u00e9gion m\u00e9diterran\u00e9enne. L&#8217;objectif est de rendre ces syst\u00e8mes, leur approvisionnement et leur gestion plus r\u00e9silients au climat, efficaces, rentables, \u00e9cologiquement et socialement durables, contribuant ainsi \u00e0 r\u00e9soudre les probl\u00e8mes de p\u00e9nurie d&#8217;eau, de s\u00e9curit\u00e9 alimentaire, de nutrition, de sant\u00e9, de bien-\u00eatre et de migration en amont.<\/p>\n<p class=\"p2\"><span class=\"s2\"><a href=\"http:\/\/www.bluemed-initiative.eu\/\" target=\"_blank\" rel=\"noopener\">BLUEMED \/ Mission \u00ab Restaurer notre Oc\u00e9an et nos Eaux d&#8217;ici 2030 \u00bb et son phare M\u00e9diterran\u00e9e z\u00e9ro pollution<\/a><\/span><\/p>\n<p class=\"p1\">L&#8217;initiative BlueMed, mise en place en mai 2014 dans le cadre de la strat\u00e9gie europ\u00e9enne sur la croissance bleue, est une initiative politique visant \u00e0 faire avancer une vision partag\u00e9e pour une mer M\u00e9diterran\u00e9e plus saine, productive, r\u00e9siliente, mieux connue et valoris\u00e9e, le bien-\u00eatre social et la prosp\u00e9rit\u00e9, aujourd&#8217;hui et pour les g\u00e9n\u00e9rations futures, et la stimulation de la croissance \u00e9conomique et de l&#8217;emploi. En 2021, le nouvel agenda strat\u00e9gique de recherche et d&#8217;innovation a \u00e9t\u00e9 \u00e9labor\u00e9, pr\u00e9parant la voie \u00e0 la mise en \u0153uvre du Lighthouse m\u00e9diterran\u00e9en du programme Horizon Europe <a href=\"https:\/\/ec.europa.eu\/info\/research-and-innovation\/funding\/funding-opportunities\/funding-programmes-and-open-calls\/horizon-europe\/eu-missions-horizon-europe\/healthy-oceans-seas-coastal-and-inland-waters_en\" target=\"_blank\" rel=\"noopener\"><span class=\"s1\">Restaurer nos oc\u00e9ans et nos eaux d&#8217;ici 2030<\/span><\/a>, \u00e9galement \u00e0 travers une cartographie compl\u00e8te des initiatives de lutte contre la pollution plastique men\u00e9es par la M\u00e9diterran\u00e9e des pays.<\/p>\n<p class=\"p2\"><span class=\"s2\"><a href=\"https:\/\/www.medecc.org\/\" target=\"_blank\" rel=\"noopener\">MEDECC \u2013 Experts M\u00e9diterran\u00e9ens en Changement Climatique et Environnemental<\/a><\/span><\/p>\n<p class=\"p1\">Les Experts M\u00e9diterran\u00e9ens sur le Changement Climatique et Environnemental (MedECC) est un r\u00e9seau international ouvert et ind\u00e9pendant d&#8217;experts scientifiques fond\u00e9 en 2015 et fournissant des informations aux d\u00e9cideurs et au grand public sur la base des informations scientifiques disponibles et des recherches en cours. MedECC pr\u00e9pare des \u00e9valuations et une synth\u00e8se compl\u00e8te des connaissances sur le changement global dans la r\u00e9gion m\u00e9diterran\u00e9enne et leurs risques.<\/p>\n<p class=\"p2\"><span class=\"s2\"><a href=\"https:\/\/www.oneplanetnetwork.org\/knowledge-centre\/projects\/sfs-med-platform\" target=\"_blank\" rel=\"noopener\">Syst\u00e8mes Alimentaires Durables \u2013 Plateforme MED<\/a><\/span><\/p>\n<p class=\"p1\">La plateforme SFS-MED est une communaut\u00e9 pour tirer parti des connaissances, de l&#8217;exp\u00e9rience et des comp\u00e9tences existantes des acteurs des syst\u00e8mes alimentaires dans la r\u00e9gion m\u00e9diterran\u00e9enne. La Plateforme SFS-MED est pilot\u00e9e par : le Centre International de Hautes Etudes Agronomiques M\u00e9diterran\u00e9ennes (CIHEAM), l&#8217;Organisation des Nations Unies pour l&#8217;Alimentation et l&#8217;Agriculture (FAO) et le Secr\u00e9tariat de l&#8217;Union pour la M\u00e9diterran\u00e9e (UpM), en collaboration avec le Partenariat pour la recherche et l&#8217;innovation dans la r\u00e9gion m\u00e9diterran\u00e9enne (PRIMA), en tant que projet affili\u00e9 au programme Syst\u00e8mes alimentaires durables du r\u00e9seau One Planet.<\/p>\n<p class=\"p2\"><span class=\"s2\"><a href=\"https:\/\/ufmsecretariat.org\/\/project\/blueskills-blue-jobs\/\" target=\"_blank\" rel=\"noopener\">BlueSkills : Emplois Bleus et Croissance Responsable en M\u00e9diterran\u00e9e<\/a><\/span><\/p>\n<p class=\"p1\">Le projet BlueSkills promeut les opportunit\u00e9s de carri\u00e8res marines et maritimes \u00ab\u00a0bleues\u00a0\u00bb en d\u00e9veloppant les comp\u00e9tences, en \u00e9changeant des connaissances et en valorisant la recherche pour une mer M\u00e9diterran\u00e9e plus durable. Son objectif est de d\u00e9velopper de nouveaux cursus et d&#8217;accro\u00eetre l&#8217;employabilit\u00e9 dans les secteurs marin et maritime. En soutenant les communaut\u00e9s euro-m\u00e9diterran\u00e9ennes des acteurs de l&#8217;\u00e9conomie bleue par l&#8217;enseignement sup\u00e9rieur, la recherche et l&#8217;innovation, le projet valorise la connaissance partag\u00e9e de la r\u00e9gion m\u00e9diterran\u00e9enne.<\/p>\n<p class=\"p1\"><b>Publications disponible<\/b><\/p>\n<p class=\"p3\"><span class=\"s2\"><a href=\"https:\/\/ufmsecretariat.org\/\/publication-speech\/take-away-ideas-report\/\" target=\"_blank\" rel=\"noopener\">Science and Innovation Diplomacy in the Mediterranean<\/a><\/span><\/p>\n<p class=\"p3\"><span class=\"s2\"><a href=\"https:\/\/ufmsecretariat.org\/\/publication-speech\/reinforcing-the-innovation-employability-nexus-in-the-mediterranean\/\" target=\"_blank\" rel=\"noopener\">Reinforcing the Innovation-Employability Nexus in the Mediterranean \u2013 A Handbook for Academia, Industry and Policymakers<\/a><\/span><\/p>\n<p class=\"p3\"><span class=\"s2\"><a href=\"https:\/\/ufmsecretariat.org\/\/publication-speech\/future-scenarios-for-euromed-agrifood\/\" target=\"_blank\" rel=\"noopener\">Future Scenarios for EuroMed Agrifood<\/a><\/span><\/p>\n<p><a href=\"https:\/\/ufmsecretariat.org\/\/wp-content\/uploads\/2022\/06\/MinisterialResearch-FamilyPicture.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-136957\" src=\"https:\/\/ufmsecretariat.org\/\/wp-content\/uploads\/2022\/06\/MinisterialResearch-FamilyPicture-300x150.jpg\" alt=\"\" width=\"782\" height=\"391\" srcset=\"https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2022\/06\/MinisterialResearch-FamilyPicture-300x150.jpg 300w, https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2022\/06\/MinisterialResearch-FamilyPicture-768x384.jpg 768w, https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2022\/06\/MinisterialResearch-FamilyPicture-1024x512.jpg 1024w, https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2022\/06\/MinisterialResearch-FamilyPicture-100x50.jpg 100w\" sizes=\"auto, (max-width: 782px) 100vw, 782px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les Ministres de la Recherche et de l&#8217;Innovation des 42 pays de l&#8217;Union pour la M\u00e9diterran\u00e9e (UpM) se sont r\u00e9unis pour la premi\u00e8re fois pour discuter des moyens de promouvoir la coop\u00e9ration scientifique sur le changement climatique, les \u00e9nergies renouvelables et la sant\u00e9. Ils ont approuv\u00e9 une d\u00e9claration minist\u00e9rielle qui vise \u00e0 exploiter le potentiel<br \/><a href=\"https:\/\/ufmsecretariat.org\/fr\/ministerial-conference-research-innovation-2022\/\" class=\"more\">Lire la suite<\/a><\/p>\n","protected":false},"author":38,"featured_media":136951,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92,85],"tags":[],"priority-area":[203],"class_list":["post-136867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-actualites-phares","priority-area-higher-education-research-fr"],"_links":{"self":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/136867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/comments?post=136867"}],"version-history":[{"count":5,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/136867\/revisions"}],"predecessor-version":[{"id":136960,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/136867\/revisions\/136960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/media\/136951"}],"wp:attachment":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/media?parent=136867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/categories?post=136867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/tags?post=136867"},{"taxonomy":"priority-area","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/priority-area?post=136867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}