

{"id":158480,"date":"2023-12-14T16:17:43","date_gmt":"2023-12-14T15:17:43","guid":{"rendered":"https:\/\/ufmsecretariat.org\/?p=158480"},"modified":"2024-01-30T12:33:06","modified_gmt":"2024-01-30T11:33:06","slug":"activities-promote-digitalisation-youth-employment","status":"publish","type":"post","link":"https:\/\/ufmsecretariat.org\/fr\/activities-promote-digitalisation-youth-employment\/","title":{"rendered":"Les activit\u00e9s de l&#8217;UpM \u00e0 Turin promeuvent la num\u00e9risation et l&#8217;emploi des jeunes"},"content":{"rendered":"<ul>\n<li><strong>Le secr\u00e9tariat de l&#8217;UpM a coorganis\u00e9 deux activit\u00e9s \u00e0 Turin, l&#8217;atelier sur l&#8217;\u00e9conomie de plateforme avec la Coop\u00e9ration allemande au d\u00e9veloppement et la Fondation europ\u00e9enne pour la formation, ainsi que la 6\u00e8me r\u00e9union de la communaut\u00e9 de pratique de l&#8217;UpM sur l&#8217;emploi des jeunes dans le sud de la M\u00e9diterran\u00e9e.<\/strong><\/li>\n<li><strong>La r\u00e9gion euro-m\u00e9diterran\u00e9enne dispose d&#8217;un \u00e9norme capital humain, mais la proportion de jeunes qui ne sont pas en situation d\u2019emploi, d\u2019\u00e9ducation ou de formation (NEET de son acronyme en anglais) reste structurellement \u00e9lev\u00e9e, en particulier en Europe du sud et dans la r\u00e9gion MENA. La num\u00e9risation et la connectivit\u00e9 restent \u00e0 la fois in\u00e9gales et insuffisantes dans le sud de la M\u00e9diterran\u00e9e.<\/strong><\/li>\n<\/ul>\n<p><strong>12-14 d\u00e9cembre 2023, Turin<\/strong> &#8211; L&#8217;Union pour la M\u00e9diterran\u00e9e s&#8217;est associ\u00e9e \u00e0 la Coop\u00e9ration allemande au d\u00e9veloppement et \u00e0 la Fondation europ\u00e9enne pour la formation pour organiser <strong>l&#8217;atelier de l&#8217;UpM sur les nouveaux secteurs \u00e9conomiques ax\u00e9s sur l&#8217;\u00e9conomie de plateforme<\/strong> \u00e0 Turin, en Italie, le 12 d\u00e9cembre 2023. L&#8217;atelier \u00e9tait consacr\u00e9 aux opportunit\u00e9s et aux menaces associ\u00e9es \u00e0 l&#8217;\u00e9conomie de plateforme en termes d&#8217;impact social et \u00e9conomique, de d\u00e9ficit de comp\u00e9tences et de r\u00e9ponses politiques.<\/p>\n<p><a href=\"https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2023\/12\/IMG_9786_turin-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-158475 alignleft\" src=\"https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2023\/12\/IMG_9786_turin-scaled-300x181.jpg\" alt=\"\" width=\"393\" height=\"237\" srcset=\"https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2023\/12\/IMG_9786_turin-scaled-300x181.jpg 300w, https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2023\/12\/IMG_9786_turin-scaled-1024x619.jpg 1024w, https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2023\/12\/IMG_9786_turin-768x464.jpg 768w, https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2023\/12\/IMG_9786_turin-scaled-1536x928.jpg 1536w, https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2023\/12\/IMG_9786_turin-2048x1237.jpg 2048w, https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2023\/12\/IMG_9786_turin-scaled.jpg 1920w\" sizes=\"auto, (max-width: 393px) 100vw, 393px\" \/><\/a><\/p>\n<p>Les participants ont identifi\u00e9 les facteurs critiques de r\u00e9ussite de l&#8217;\u00e9conomie de plateforme et le potentiel de l&#8217;entrepreneuriat dans la r\u00e9gion, dont les recommandations devraient influencer la prochaine conf\u00e9rence de l&#8217;UpM sur la transformation num\u00e9rique, qui se tiendra les 18 et 19 d\u00e9cembre 2023 \u00e0 Tanger, au Maroc.<\/p>\n<p>Cet \u00e9v\u00e9nement a \u00e9t\u00e9 suivi, les 13 et 14 d\u00e9cembre 2023, par la <strong>6\u00e8me r\u00e9union de la communaut\u00e9 de pratique de l&#8217;UpM sur l&#8217;emploi des jeunes dans le sud de la M\u00e9diterran\u00e9e<\/strong> dans les locaux de l&#8217;ETF (Fondation europ\u00e9enne pour la formation) \u00e0 Turin. Cette rencontre \u00e9tait ax\u00e9e sur l&#8217;apprentissage par le travail, l&#8217;orientation professionnelle et le conseil, ainsi que sur le d\u00e9veloppement des comp\u00e9tences pour les nouvelles formes de travail. Les participants ont visit\u00e9 <a href=\"https:\/\/talentgarden.org\/fr\/\">Talent Garden<\/a>, une organisation qui promeut les opportunit\u00e9s d&#8217;apprentissage et de mise en r\u00e9seau dans l&#8217;\u00e9cosyst\u00e8me num\u00e9rique, et <a href=\"https:\/\/ogrtorino.it\/en\/project\">OGR &#8211; Officine Grandi Riparazioni<\/a>, un centre d\u00e9di\u00e9 \u00e0 la culture contemporaine, l&#8217;innovation et l&#8217;acc\u00e9l\u00e9ration des entreprises.<\/p>\n<p>Ces \u00e9v\u00e9nements sont une r\u00e9ponse \u00e0 la <a href=\"https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2022\/05\/Final-UfM-Ministerial-Declaration-FR.pdf\">d\u00e9claration minist\u00e9rielle<\/a> \u00e9manant de la <a href=\"https:\/\/ufmsecretariat.org\/fr\/ministerial-meeting-employment-2022\/\">r\u00e9union minist\u00e9rielle de l&#8217;UpM sur l&#8217;emploi et le travail \u00e0 Marrakech en 2022<\/a>, qui a reconnu les d\u00e9fis associ\u00e9s aux plateformes num\u00e9riques de travail et a soulign\u00e9 la n\u00e9cessit\u00e9 de <em>\u00ab veiller \u00e0 ce que chacun puisse r\u00e9aliser son potentiel et contribuer \u00e0 la transformation num\u00e9rique de la soci\u00e9t\u00e9 \u00bb<\/em>, tout en signalant \u00e9galement un d\u00e9sir <em>\u00ab d\u2019\u00e9changer les bonnes pratiques sur les nouvelles formes de travail, telles que le t\u00e9l\u00e9travail et le travail sur les plateformes num\u00e9riques de travail \u00bb.<\/em><\/p>\n<p><strong><a href=\"https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2023\/12\/Outcome-Document-UfM-Platform-Economy-Workshop-Turin-12Dec2023.pdf\">Document de synth\u00e8se : Atelier de l&#8217;UpM sur les nouvelles formes de travail : \u00c9conomie de plateforme 12 d\u00e9cembre 2023-Turin, Italie<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2023\/12\/Outcome-Document-6th-UfM-Meeting-of-the-CoP-on-Youth-Employment-Turin-13-14Dec2023.pdf\">Document de synth\u00e8se : 6\u00e8me r\u00e9union de la Communaut\u00e9 de pratique de l&#8217;UpM sur l&#8217;emploi des jeunes dans le sud de la M\u00e9diterran\u00e9e 13-14 d\u00e9cembre 2023 &#8211; Turin, Italie<\/a><\/strong><\/p>\n<p><a title=\"Back-to-Back Activities to Promote Digitalisation and Youth Employment - 12-14 December 2023, Turin\" href=\"https:\/\/www.flickr.com\/photos\/ufms\/albums\/72177720313369835\" data-flickr-embed=\"true\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/live.staticflickr.com\/65535\/53397062241_99fc5fb628_z.jpg\" alt=\"Back-to-Back Activities to Promote Digitalisation and Youth Employment - 12-14 December 2023, Turin\" width=\"640\" height=\"480\" \/><\/a><script async src=\"\/\/embedr.flickr.com\/assets\/client-code.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le secr\u00e9tariat de l&#8217;UpM a coorganis\u00e9 deux activit\u00e9s \u00e0 Turin, l&#8217;atelier sur l&#8217;\u00e9conomie de plateforme avec la Coop\u00e9ration allemande au d\u00e9veloppement et la Fondation europ\u00e9enne pour la formation, ainsi que la 6\u00e8me r\u00e9union de la communaut\u00e9 de pratique de l&#8217;UpM sur l&#8217;emploi des jeunes dans le sud de la M\u00e9diterran\u00e9e. La r\u00e9gion euro-m\u00e9diterran\u00e9enne dispose d&#8217;un<br \/><a href=\"https:\/\/ufmsecretariat.org\/fr\/activities-promote-digitalisation-youth-employment\/\" class=\"more\">Lire la suite<\/a><\/p>\n","protected":false},"author":38,"featured_media":158471,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92,85],"tags":[],"priority-area":[193],"class_list":["post-158480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-actualites-phares","priority-area-business-development-fr"],"_links":{"self":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/158480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/comments?post=158480"}],"version-history":[{"count":10,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/158480\/revisions"}],"predecessor-version":[{"id":159544,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/158480\/revisions\/159544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/media\/158471"}],"wp:attachment":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/media?parent=158480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/categories?post=158480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/tags?post=158480"},{"taxonomy":"priority-area","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/priority-area?post=158480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}