

{"id":158676,"date":"2023-12-20T10:18:47","date_gmt":"2023-12-20T09:18:47","guid":{"rendered":"https:\/\/ufmsecretariat.org\/?p=158676"},"modified":"2024-01-30T12:19:48","modified_gmt":"2024-01-30T11:19:48","slug":"study-visit-swedish-entrepreneurial-ecosystem","status":"publish","type":"post","link":"https:\/\/ufmsecretariat.org\/fr\/study-visit-swedish-entrepreneurial-ecosystem\/","title":{"rendered":"L&#8217;UpM organise une visite d&#8217;\u00e9tude de l&#8217;\u00e9cosyst\u00e8me entrepreneurial su\u00e9dois pour les professionnels de la r\u00e9gion MENA"},"content":{"rendered":"<p><strong>5-7 d\u00e9cembre 2023, Su\u00e8de<\/strong> &#8211; L&#8217;Union pour la M\u00e9diterran\u00e9e a organis\u00e9 une visite d&#8217;\u00e9tude dans des entreprises su\u00e9doises destin\u00e9e aux professionnels des secteurs public et priv\u00e9 de la r\u00e9gion sud-m\u00e9diterran\u00e9enne. Cette visite a \u00e9t\u00e9 r\u00e9alis\u00e9e avec le soutien de la Coop\u00e9ration allemande au d\u00e9veloppement et en partenariat avec le minist\u00e8re des Affaires \u00e9trang\u00e8res de Su\u00e8de et l&#8217;Agence su\u00e9doise de coop\u00e9ration internationale au d\u00e9veloppement.<\/p>\n<p>Les participants venus d&#8217;Alg\u00e9rie, d&#8217;\u00c9gypte, de Jordanie, du Liban, du Maroc et de Tunisie ont pu s&#8217;immerger dans l&#8217;\u00e9cosyst\u00e8me entrepreneurial du pays, acqu\u00e9rir les bonnes pratiques et se constituer un r\u00e9seau.<\/p>\n<p>Des r\u00e9unions ont \u00e9t\u00e9 organis\u00e9es avec un large \u00e9ventail d&#8217;acteurs su\u00e9dois qui ont fait part de leur exp\u00e9rience en mati\u00e8re de commerce et d&#8217;aide au d\u00e9veloppement, de politiques de soutien gouvernemental, d&#8217;\u00e9cosyst\u00e8me de l&#8217;innovation, d&#8217;acc\u00e8s au march\u00e9 et au financement, ainsi que de plaidoyer.<\/p>\n<p>Le dernier jour de leur s\u00e9jour, les participants ont visit\u00e9 l&#8217;universit\u00e9 d&#8217;Uppsala, o\u00f9 ils ont discut\u00e9 de l&#8217;\u00e9cosyst\u00e8me de la ville ax\u00e9 sur l&#8217;innovation, notamment en encourageant l&#8217;esprit d&#8217;entreprise chez les \u00e9tudiants, l&#8217;incubation, le financement et la collaboration entre les chercheurs et les entreprises.<\/p>\n<p>Cette initiative est conforme \u00e0 l&#8217;engagement de l&#8217;UpM de promouvoir le secteur priv\u00e9 en tant qu&#8217;acteur cl\u00e9 pour parvenir \u00e0 un d\u00e9veloppement \u00e9conomique et humain durable et inclusif, qui constitue un objectif prioritaire de l&#8217;UpM pour les ann\u00e9es \u00e0 venir.<\/p>\n<p><a title=\"Study trip to Sweden for entrepreneurs and business support organizations\" href=\"https:\/\/www.flickr.com\/photos\/ufms\/albums\/72177720313302185\" data-flickr-embed=\"true\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/live.staticflickr.com\/65535\/53389747002_c63c7caa25_z.jpg\" alt=\"Study trip to Sweden for entrepreneurs and business support organizations\" width=\"640\" height=\"480\" \/><\/a><script async src=\"\/\/embedr.flickr.com\/assets\/client-code.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>5-7 d\u00e9cembre 2023, Su\u00e8de &#8211; L&#8217;Union pour la M\u00e9diterran\u00e9e a organis\u00e9 une visite d&#8217;\u00e9tude dans des entreprises su\u00e9doises destin\u00e9e aux professionnels des secteurs public et priv\u00e9 de la r\u00e9gion sud-m\u00e9diterran\u00e9enne. Cette visite a \u00e9t\u00e9 r\u00e9alis\u00e9e avec le soutien de la Coop\u00e9ration allemande au d\u00e9veloppement et en partenariat avec le minist\u00e8re des Affaires \u00e9trang\u00e8res de Su\u00e8de<br \/><a href=\"https:\/\/ufmsecretariat.org\/fr\/study-visit-swedish-entrepreneurial-ecosystem\/\" class=\"more\">Lire la suite<\/a><\/p>\n","protected":false},"author":38,"featured_media":158673,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92,85],"tags":[],"priority-area":[193],"class_list":["post-158676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-actualites-phares","priority-area-business-development-fr"],"_links":{"self":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/158676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/comments?post=158676"}],"version-history":[{"count":6,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/158676\/revisions"}],"predecessor-version":[{"id":159538,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/158676\/revisions\/159538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/media\/158673"}],"wp:attachment":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/media?parent=158676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/categories?post=158676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/tags?post=158676"},{"taxonomy":"priority-area","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/priority-area?post=158676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}