

{"id":163298,"date":"2024-05-15T12:40:42","date_gmt":"2024-05-15T11:40:42","guid":{"rendered":"https:\/\/ufmsecretariat.org\/?p=163298"},"modified":"2024-05-27T12:37:04","modified_gmt":"2024-05-27T11:37:04","slug":"strengthening-fruitful-partnership-with-german-development-cooperation","status":"publish","type":"post","link":"https:\/\/ufmsecretariat.org\/fr\/strengthening-fruitful-partnership-with-german-development-cooperation\/","title":{"rendered":"Renforcer le partenariat fructueux avec la Coop\u00e9ration allemande au d\u00e9veloppement"},"content":{"rendered":"<ul>\n<li><strong>La Coop\u00e9ration allemande au d\u00e9veloppement est \u00e0 ce jour le principal donateur du Secr\u00e9tariat de l&#8217;UpM, dont elle soutient les activit\u00e9s par l&#8217;interm\u00e9diaire du Hub de l&#8217;UpM pour l&#8217;emploi, le commerce et l&#8217;investissement, lequel fait partie int\u00e9grante de l&#8217;initiative Team Europe (TEI) \u00ab\u00a0L&#8217;emploi gr\u00e2ce au commerce et \u00e0 l&#8217;investissement dans le voisinage Sud \u00bb.<\/strong><\/li>\n<li><strong>Alors que le partenariat entre le Secr\u00e9tariat de l&#8217;UpM et la Coop\u00e9ration allemande au d\u00e9veloppement entre dans sa sixi\u00e8me ann\u00e9e, plusieurs bonnes pratiques peuvent \u00eatre mises \u00e0 profit et de nouvelles synergies et compl\u00e9mentarit\u00e9s peuvent \u00eatre envisag\u00e9es pour l\u2019avenir.<\/strong><\/li>\n<\/ul>\n<p><strong>Berlin, Allemagne, 15 mai 2024. <\/strong>Alors que le partenariat entre le Secr\u00e9tariat de l&#8217;UpM et la Coop\u00e9ration allemande au d\u00e9veloppement entre dans sa 6e ann\u00e9e, le secr\u00e9taire g\u00e9n\u00e9ral de l&#8217;UpM, Nasser Kamel, a entam\u00e9 une visite de travail \u00e0 Berlin, en Allemagne, o\u00f9 il a tenu des r\u00e9unions avec M. Carsten Schmitz-Hoffmann, directeur g\u00e9n\u00e9ral pour l&#8217;Europe, la M\u00e9diterran\u00e9e et l&#8217;Asie centrale \u00e0 la <a href=\"https:\/\/www.giz.de\/en\/html\/index.html\" target=\"_blank\" rel=\"noopener\">Soci\u00e9t\u00e9 allemande pour la coop\u00e9ration internationale (GIZ)<\/a>. Le secr\u00e9taire g\u00e9n\u00e9ral de l&#8217;UpM, M. Kamel, a salu\u00e9 l&#8217;engagement de la GIZ comme une \u00e9quipe pleinement int\u00e9gr\u00e9e au secr\u00e9tariat de l&#8217;UpM, un exemple qui a suscit\u00e9 l&#8217;int\u00e9r\u00eat d&#8217;autres donateurs et agences de coop\u00e9ration au d\u00e9veloppement. En r\u00e9ponse, M. Schmitz-Hoffman a soulign\u00e9 l\u2019importance du r\u00f4le de l&#8217;UpM qui, en raison de sa port\u00e9e g\u00e9ographique et th\u00e9matique, est particuli\u00e8rement bien plac\u00e9e pour promouvoir la coop\u00e9ration et les \u00e9changes r\u00e9gionaux au niveau politique et technique.<\/p>\n<div id=\"attachment_163288\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2024\/05\/2-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-163288\" class=\"wp-image-163288 size-medium\" src=\"https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2024\/05\/2-scaled.jpg\" alt=\"\" width=\"300\" height=\"233\" srcset=\"https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2024\/05\/2-scaled.jpg 1920w, https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2024\/05\/2-scaled-300x233.jpg 300w, https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2024\/05\/2-scaled-1024x794.jpg 1024w, https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2024\/05\/2-768x595.jpg 768w, https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2024\/05\/2-scaled-1536x1190.jpg 1536w, https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2024\/05\/2-2048x1587.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-163288\" class=\"wp-caption-text\">Le secr\u00e9taire g\u00e9n\u00e9ral de l&#8217;UpM, Nasser Kamel, avec M. Christoph Rauh, directeur Afrique au minist\u00e8re f\u00e9d\u00e9ral allemand de la Coop\u00e9ration \u00e9conomique et du d\u00e9veloppement (BMZ).<\/p><\/div>\n<p>Cette rencontre a \u00e9t\u00e9 suivie d&#8217;une r\u00e9union avec M. Christoph Rauh, directeur Afrique au <a href=\"https:\/\/www.bmz.de\/en\" target=\"_blank\" rel=\"noopener\">minist\u00e8re f\u00e9d\u00e9ral allemand de la Coop\u00e9ration \u00e9conomique et du d\u00e9veloppement (BMZ),<\/a> afin de faire le point sur les progr\u00e8s accomplis et les perspectives de renforcement du partenariat existant \u00e0 l&#8217;avenir. Au cours de la r\u00e9union, le SG de l&#8217;UpM, Nasser Kamel, a d\u00e9clar\u00e9\u00a0: <em>\u00ab\u00a0ce partenariat a permis \u00e0 l&#8217;UpM de faire un bond en avant dans sa capacit\u00e9 \u00e0 atteindre ses objectifs et \u00e0 s&#8217;engager dans un \u00e9cosyst\u00e8me de plus en plus large, \u00e0 progresser dans sa courbe d&#8217;apprentissage et \u00e0 remplir son mandat malgr\u00e9 les perturbations successives dans la r\u00e9gion\u00a0\u00bb. <\/em>Pour sa part, M. Rauh a d\u00e9clar\u00e9 que \u00ab\u00a0<em>le partenariat continu avec l&#8217;UpM et ses \u00c9tats membres comporte d&#8217;\u00e9normes avantages comparatifs dans la dimension du d\u00e9veloppement, notamment en facilitant les perspectives \u00e9conomiques pour les investissements, le commerce et l&#8217;emploi<\/em>\u00a0\u00bb.<\/p>\n<div id=\"attachment_163291\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2024\/05\/3-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-163291\" class=\"wp-image-163291 size-medium\" src=\"https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2024\/05\/3-scaled.jpg\" alt=\"\" width=\"300\" height=\"217\" srcset=\"https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2024\/05\/3-scaled.jpg 1920w, https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2024\/05\/3-scaled-300x217.jpg 300w, https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2024\/05\/3-scaled-1024x741.jpg 1024w, https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2024\/05\/3-768x556.jpg 768w, https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2024\/05\/3-scaled-1536x1111.jpg 1536w, https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2024\/05\/3-2048x1482.jpg 2048w, https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2024\/05\/3-553x400.jpg 553w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-163291\" class=\"wp-caption-text\">Le secr\u00e9taire g\u00e9n\u00e9ral de l&#8217;UpM, Nasser Kamel, avec Dr. B\u00e4rbel Kofler, secr\u00e9taire d&#8217;\u00c9tat parlementaire aupr\u00e8s du Ministre f\u00e9d\u00e9ral allemand de la Coop\u00e9ration \u00e9conomique et du D\u00e9veloppement (BMZ)<\/p><\/div>\n<p>Dans le cadre de sa visite de travail, le SG de l&#8217;UpM, Nasser Kamel, s&#8217;est \u00e9galement entretenu avec le Dr. B\u00e4rbel Kofler, secr\u00e9taire d&#8217;\u00c9tat parlementaire aupr\u00e8s du Ministre f\u00e9d\u00e9ral allemand de la Coop\u00e9ration \u00e9conomique et du D\u00e9veloppement (BMZ).<\/p>\n<p>Le partenariat de la Coop\u00e9ration allemande au d\u00e9veloppement avec le secr\u00e9tariat de l&#8217;UpM a d\u00e9but\u00e9 en 2018 avec un mandat de quatre ans qui a \u00e9t\u00e9 renouvel\u00e9 pour trois ann\u00e9es suppl\u00e9mentaires en 2022 avec le lancement du <a href=\"https:\/\/ufmsecretariat.org\/fr\/ufm-launches-regional-hub-jobs-trade-investment\/\" target=\"_blank\" rel=\"noopener\"><strong>Hub de l&#8217;UpM pour l&#8217;emploi, le commerce et l&#8217;investissement<\/strong><\/a> (2022-2025), qui est enti\u00e8rement align\u00e9 sur les piliers de l&#8217;<a href=\"https:\/\/capacity4dev.europa.eu\/resources\/team-europe-tracker_en\" target=\"_blank\" rel=\"noopener\"><strong>initiative<\/strong><\/a> r\u00e9gionale <a href=\"https:\/\/capacity4dev.europa.eu\/resources\/team-europe-tracker_en\" target=\"_blank\" rel=\"noopener\"><strong>Team Europe \u00ab Emplois gr\u00e2ce au commerce et \u00e0 l&#8217;investissement dans le voisinage Sud \u00bb<\/strong><\/a><strong>.<\/strong> Gr\u00e2ce \u00e0 ce partenariat, le secr\u00e9tariat de l&#8217;UpM a pu \u00e9tendre son travail \u00e0 de nouveaux domaines prioritaires et mettre en place un engagement r\u00e9gional structur\u00e9, notamment dans des domaines tels que l&#8217;investissement durable, la facilitation du commerce, la cr\u00e9ation d&#8217;emplois, le d\u00e9veloppement des comp\u00e9tences et l&#8217;autonomisation socio-\u00e9conomique des femmes. Le partenariat a donn\u00e9 lieu \u00e0 de nombreux r\u00e9sultats concrets, notamment le d\u00e9veloppement de plusieurs dialogues multipartites de haut niveau, la mise en \u0153uvre de nombreuses formations et ateliers pour les parties prenantes gouvernementales et non gouvernementales dans les \u00c9tats membres de l&#8217;UpM, le d\u00e9veloppement de programmes de subventions pour les organisations \u00e0 but non lucratif, et le d\u00e9veloppement des connaissances par le biais de rapports complets sur l&#8217;int\u00e9gration r\u00e9gionale dans tous les domaines politiques de l&#8217;UpM.<\/p>\n<p><strong>Plus d&#8217;informations<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/ufmsecretariat.org\/ufm-grant-schemes\/\" target=\"_blank\" rel=\"noopener\">Programmes de subventions de l&#8217;UpM<\/a><\/li>\n<li><a href=\"https:\/\/ufmsecretariat.org\/fr\/notre-action\/business-development\/\" target=\"_blank\" rel=\"noopener\">Division du d\u00e9veloppement \u00e9conomique et de l&#8217;emploi de l&#8217;UPM<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La Coop\u00e9ration allemande au d\u00e9veloppement est \u00e0 ce jour le principal donateur du Secr\u00e9tariat de l&#8217;UpM, dont elle soutient les activit\u00e9s par l&#8217;interm\u00e9diaire du Hub de l&#8217;UpM pour l&#8217;emploi, le commerce et l&#8217;investissement, lequel fait partie int\u00e9grante de l&#8217;initiative Team Europe (TEI) \u00ab\u00a0L&#8217;emploi gr\u00e2ce au commerce et \u00e0 l&#8217;investissement dans le voisinage Sud \u00bb. Alors<br \/><a href=\"https:\/\/ufmsecretariat.org\/fr\/strengthening-fruitful-partnership-with-german-development-cooperation\/\" class=\"more\">Lire la suite<\/a><\/p>\n","protected":false},"author":38,"featured_media":163287,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92,85],"tags":[],"priority-area":[12782,193,18246],"class_list":["post-163298","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-actualites-phares","priority-area-activity-of-the-secretary-general-fr","priority-area-business-development-fr","priority-area-institutional-fr"],"_links":{"self":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/163298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/comments?post=163298"}],"version-history":[{"count":5,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/163298\/revisions"}],"predecessor-version":[{"id":163625,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/163298\/revisions\/163625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/media\/163287"}],"wp:attachment":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/media?parent=163298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/categories?post=163298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/tags?post=163298"},{"taxonomy":"priority-area","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/priority-area?post=163298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}