

{"id":17440,"date":"2015-06-09T15:21:28","date_gmt":"2015-06-09T14:21:28","guid":{"rendered":"https:\/\/ufmsecretariat.org\/ufm-and-businessmed-join-forces-to-accelerate-economic-development-in-the-mediterranean-2\/"},"modified":"2015-06-22T12:49:11","modified_gmt":"2015-06-22T11:49:11","slug":"ufm-and-businessmed-join-forces-to-accelerate-economic-development-in-the-mediterranean","status":"publish","type":"post","link":"https:\/\/ufmsecretariat.org\/fr\/ufm-and-businessmed-join-forces-to-accelerate-economic-development-in-the-mediterranean\/","title":{"rendered":"L\u2019UpM et Businessmed unissent leurs forces pour acc\u00e9l\u00e9rer le d\u00e9veloppement \u00e9conomique en M\u00e9diterran\u00e9e"},"content":{"rendered":"<p><strong>\u00c0 Barcelone, le 9\u00a0juin\u00a02015<\/strong>. Le d\u00e9veloppement du secteur priv\u00e9 est indispensable pour saisir les opportunit\u00e9s commerciales existantes et pour promouvoir l&#8217;int\u00e9gration r\u00e9gionale en M\u00e9diterran\u00e9e, en augmentant les niveaux actuels du commerce intra-r\u00e9gional, qui ne repr\u00e9sente que 5\u00a0% du commerce ext\u00e9rieur total des pays du sud de la M\u00e9diterran\u00e9e, un chiffre encore tr\u00e8s bas compar\u00e9 aux 65\u00a0% des pays de l&#8217;UE, aux 22\u00a0% des pays de l&#8217;ASEAN et aux 19\u00a0% des pays du MERCOSUR.<\/p>\n<p>L&#8217;accord sign\u00e9 entre le Secr\u00e9tariat de l&#8217;UpM et Businessmed vise \u00e0 soutenir le d\u00e9veloppement du monde des affaires m\u00e9diterran\u00e9en et \u00e0 faire progresser les m\u00e9canismes de collaboration con\u00e7us pour mieux comprendre le secteur priv\u00e9 au sein de la r\u00e9gion et les d\u00e9fis auxquels sont confront\u00e9es les micro, petites et moyennes entreprises, qui repr\u00e9sentent 90\u00a0% des soci\u00e9t\u00e9s existantes dans ces pays. Les deux institutions coop\u00e9reront sur des activit\u00e9s sp\u00e9cifiques afin d&#8217;aider au d\u00e9veloppement d&#8217;un environnement propice aux investissements et promouvoir ainsi les initiatives du secteur priv\u00e9 qui peuvent contribuer \u00e0 une croissance \u00e9conomique stable, durable et orient\u00e9e sur le long terme.<\/p>\n<p>Le protocole d&#8217;accord a \u00e9t\u00e9 sign\u00e9 aujourd&#8217;hui par le Secr\u00e9taire g\u00e9n\u00e9ral de l&#8217;UpM, M.\u00a0Fathallah Sijilmassi, et par le pr\u00e9sident de Businessmed, M.\u00a0Jacques Jean Sarraf, au si\u00e8ge de l&#8217;UpM, \u00e0 Barcelone.<\/p>\n<p>Cet accord s&#8217;inscrit dans le cadre de la strat\u00e9gie de l&#8217;UpM visant \u00e0 renforcer les relations avec le secteur priv\u00e9 et \u00e0 promouvoir une croissance inclusive et une int\u00e9gration plus pouss\u00e9e au sein de la r\u00e9gion euro-m\u00e9diterran\u00e9enne. Le Secr\u00e9tariat de l&#8217;UpM cherche \u00e0 encourager la participation du secteur priv\u00e9 aux initiatives et projets de l&#8217;UpM pour la mise \u00e0 disposition d&#8217;une expertise et d&#8217;un engagement au sein des projets, des contribution financi\u00e8res \u00e9ventuelles et le d\u00e9veloppement de nouvelles initiatives dans les domaines d&#8217;action du Secr\u00e9tariat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Secr\u00e9tariat de l&#8217;Union pour la M\u00e9diterran\u00e9e (UpM) et l&#8217;Union M\u00e9diterran\u00e9enne des Conf\u00e9d\u00e9rations d&#8217;Entreprises (Businessmed) ont sign\u00e9 un accord pour renforcer la contribution du secteur priv\u00e9 au d\u00e9veloppement socio-\u00e9conomique de la r\u00e9gion m\u00e9diterran\u00e9enne.<\/p>\n","protected":false},"author":3,"featured_media":17438,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92,85,76],"tags":[],"priority-area":[193],"class_list":["post-17440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-actualites-phares","category-developpement-des-entreprises","priority-area-business-development-fr"],"_links":{"self":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/17440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/comments?post=17440"}],"version-history":[{"count":2,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/17440\/revisions"}],"predecessor-version":[{"id":17614,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/17440\/revisions\/17614"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/media\/17438"}],"wp:attachment":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/media?parent=17440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/categories?post=17440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/tags?post=17440"},{"taxonomy":"priority-area","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/priority-area?post=17440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}