

{"id":177348,"date":"2024-10-28T15:42:39","date_gmt":"2024-10-28T14:42:39","guid":{"rendered":"https:\/\/ufmsecretariat.org\/?p=177348"},"modified":"2024-10-28T18:04:23","modified_gmt":"2024-10-28T17:04:23","slug":"9th-ufm-regional-forum","status":"publish","type":"post","link":"https:\/\/ufmsecretariat.org\/fr\/9th-ufm-regional-forum\/","title":{"rendered":"Les ministres des Affaires \u00e9trang\u00e8res de l&#8217;UpM se r\u00e9unissent \u00e0 Barcelone pour renforcer la coop\u00e9ration euro-m\u00e9diterran\u00e9enne dans un contexte de tensions r\u00e9gionales"},"content":{"rendered":"<ul>\n<li><strong>Des repr\u00e9sentants des 43 \u00c9tats membres de l&#8217;Union pour la M\u00e9diterran\u00e9e (UpM) ont particip\u00e9 \u00e0 leur 9e Forum r\u00e9gional pour discuter de la situation critique au Moyen-Orient et de la r\u00e9forme de l&#8217;organisation.<\/strong><\/li>\n<li><strong>L&#8217;\u00e9v\u00e9nement a \u00e9t\u00e9 pr\u00e9sid\u00e9 par Josep Borrell, haut repr\u00e9sentant pour les Affaires \u00e9trang\u00e8res et la politique de s\u00e9curit\u00e9 et vice-pr\u00e9sident de la Commission europ\u00e9enne, et Ayman Safadi, vice-premier ministre et ministre des Affaires \u00e9trang\u00e8res et des expatri\u00e9s de Jordanie. Il a \u00e9t\u00e9 accueilli par Jos\u00e9 Manuel Albares, ministre des Affaires \u00e9trang\u00e8res, de l&#8217;Union europ\u00e9enne et de la Coop\u00e9ration de l&#8217;Espagne, en pr\u00e9sence de Nasser Kamel, secr\u00e9taire g\u00e9n\u00e9ral de l&#8217;Union pour la M\u00e9diterran\u00e9e.\u00a0Waleed bin Abdulkarim El-Khereiji, vice-ministre des Affaires \u00e9trang\u00e8res du Royaume d&#8217;Arabie saoudite, repr\u00e9sentait le Comit\u00e9 minist\u00e9riel arabo-islamique. Nadia Calvi\u00f1o, pr\u00e9sidente de la Banque europ\u00e9enne d&#8217;investissement, \u00e9tait pr\u00e9sente. Salvador Illa, pr\u00e9sident du gouvernement de la Catalogne, a particip\u00e9 \u00e0 l&#8217;accueil des d\u00e9l\u00e9gations.<\/strong><\/li>\n<li><strong>Lanc\u00e9e en 2008 sur l\u2019h\u00e9ritage du Processus de Barcelone, issu de l\u2019espoir des Accords d\u2019Oslo, l\u2019objectif principal de l\u2019Union pour la M\u00e9diterran\u00e9e est de promouvoir le dialogue et la coop\u00e9ration r\u00e9gionale afin de cr\u00e9er une r\u00e9gion euro-m\u00e9diterran\u00e9enne plus pacifique, stable et prosp\u00e8re.<\/strong><\/li>\n<\/ul>\n<p><strong>Barcelone, 28 octobre 2024. <\/strong>Le 9e Forum r\u00e9gional de l\u2019Union pour la M\u00e9diterran\u00e9e, centr\u00e9 sur la situation pr\u00e9occupante au Moyen-Orient ainsi que sur la r\u00e9forme de l\u2019organisation, s\u2019est tenu aujourd&#8217;hui \u00e0 Barcelone.<\/p>\n<p>L&#8217;UpM est profond\u00e9ment pr\u00e9occup\u00e9e par la grave catastrophe humanitaire dans la r\u00e9gion et s&#8217;engage \u00e0 jouer un r\u00f4le actif \u00e0 Gaza d\u00e8s que la reconstruction sera possible. Elle a d\u00e9j\u00e0 entam\u00e9 l\u2019appui \u00e0 des initiatives en ce sens, notamment l\u2019Initiative de Soutien Technique \u00e0 l&#8217;\u00c9ducation pour les \u00c9tudiants de l&#8217;Enseignement Sup\u00e9rieur \u2013 TESI de UNIMED et de l&#8217;Universit\u00e9 Nationale An-Najah qui permettra \u00e0 quelque 50 000 \u00e9tudiants palestiniens de l\u2019enseignement sup\u00e9rieur de terminer leurs \u00e9tudes en ligne, et elle explore d&#8217;autres actions potentielles dans les domaines de l&#8217;emploi, du nexus eau-alimentation-\u00e9nergie-\u00e9cosyst\u00e8me (WEFE) et du d\u00e9veloppement urbain.<\/p>\n<p><em>\u00ab Au cours de mes quatre d\u00e9cennies de service, j\u2019ai \u00e9t\u00e9 t\u00e9moin d\u2019innombrables crises et conflits, mais jamais je n\u2019ai rencontr\u00e9 une trag\u00e9die aussi profonde que celle qui ravage actuellement la r\u00e9gion m\u00e9diterran\u00e9enne. Le bilan humanitaire est accablant, avec des vies perdues et des familles bris\u00e9es. L\u2019urgence d\u2019une action significative n\u2019a jamais \u00e9t\u00e9 aussi pressante \u00bb, <\/em>a d\u00e9clar\u00e9 <strong>Nasser Kamel, secr\u00e9taire g\u00e9n\u00e9ral de l\u2019Union pour la M\u00e9diterran\u00e9e<\/strong>.<\/p>\n<p><em>\u00ab Il n\u2019y a pas de raccourcis vers la paix ; c\u2019est un chemin qui exige dialogue, volont\u00e9 politique et solutions \u00e9quitables. Dans ces moments difficiles, l\u2019Union pour la M\u00e9diterran\u00e9e s\u2019efforce de remplir sa mission, dans la conviction que le renforcement de la coop\u00e9ration r\u00e9gionale peut offrir des lueurs d\u2019espoir \u00bb, <\/em>a-t-il ajout\u00e9.<\/p>\n<p>Fond\u00e9e sur l\u2019h\u00e9ritage du Processus de Barcelone et ses objectifs de paix, de stabilit\u00e9 et de prosp\u00e9rit\u00e9 partag\u00e9es dans la r\u00e9gion euro-m\u00e9diterran\u00e9enne, l\u2019UpM repr\u00e9sente un cadre institutionnel multilat\u00e9ral de premier plan pour le dialogue et la coop\u00e9ration en M\u00e9diterran\u00e9e. L\u2019institution d\u00e9veloppe des projets et initiatives visant \u00e0 renforcer le r\u00f4le des femmes et des jeunes, cr\u00e9er des emplois, faciliter le commerce et le d\u00e9veloppement urbain, ainsi qu\u2019\u00e0 engager des actions contre le changement climatique et pour la protection de l\u2019environnement.<\/p>\n<p>Le processus de r\u00e9forme de l\u2019UpM, lanc\u00e9 en 2023 \u00e0 l\u2019occasion de son 15\u1d49 anniversaire, vise \u00e0 renforcer le mandat de l&#8217;organisation, ses capacit\u00e9s d\u2019action et ses ressources. Le premier paquet de r\u00e9forme a permis de rationaliser ses plateformes de dialogue r\u00e9gional et d&#8217;am\u00e9liorer la communication avec les \u00c9tats membres. La deuxi\u00e8me phase, initi\u00e9e cette ann\u00e9e, s\u2019est concentr\u00e9e sur la r\u00e9flexion autour des priorit\u00e9s et de la vision futures de l&#8217;UpM. Lors du 9\u1d49 Forum r\u00e9gional, les ministres ont d\u00e9battu de ces priorit\u00e9s dans un contexte r\u00e9gional en \u00e9volution, reconnaissant le r\u00f4le crucial de l\u2019UpM, son pouvoir de rassemblement, et son engagement permanent pour la cause euro-m\u00e9diterran\u00e9enne.<\/p>\n<p><a href=\"https:\/\/ufmsecretariat.org\/wp-content\/uploads\/2024\/10\/9th-UfM-Regional-Forum-Co-presidency-joint-statement.pdf\"><strong>Co-chairs\u2019 official statement<\/strong><\/a><\/p>\n<p><a title=\"9th UfM Regional Forum 2024\" href=\"https:\/\/www.flickr.com\/photos\/ufms\/albums\/72177720321556139\" data-flickr-embed=\"true\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/live.staticflickr.com\/65535\/54099390723_f19f00a69b_z.jpg\" alt=\"9th UfM Regional Forum 2024\" width=\"640\" height=\"480\" \/><\/a><script async src=\"\/\/embedr.flickr.com\/assets\/client-code.js\" charset=\"utf-8\"><\/script><\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/rFCyd-ZLX00?si=KUAWUCxVxttTKnyp\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des repr\u00e9sentants des 43 \u00c9tats membres de l&#8217;Union pour la M\u00e9diterran\u00e9e (UpM) ont particip\u00e9 \u00e0 leur 9e Forum r\u00e9gional pour discuter de la situation critique au Moyen-Orient et de la r\u00e9forme de l&#8217;organisation. L&#8217;\u00e9v\u00e9nement a \u00e9t\u00e9 pr\u00e9sid\u00e9 par Josep Borrell, haut repr\u00e9sentant pour les Affaires \u00e9trang\u00e8res et la politique de s\u00e9curit\u00e9 et vice-pr\u00e9sident de la<br \/><a href=\"https:\/\/ufmsecretariat.org\/fr\/9th-ufm-regional-forum\/\" class=\"more\">Lire la suite<\/a><\/p>\n","protected":false},"author":38,"featured_media":177345,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92,85],"tags":[],"priority-area":[18246],"class_list":["post-177348","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-actualites-phares","priority-area-institutional-fr"],"_links":{"self":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/177348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/comments?post=177348"}],"version-history":[{"count":6,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/177348\/revisions"}],"predecessor-version":[{"id":177388,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/177348\/revisions\/177388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/media\/177345"}],"wp:attachment":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/media?parent=177348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/categories?post=177348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/tags?post=177348"},{"taxonomy":"priority-area","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/priority-area?post=177348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}