

{"id":185771,"date":"2024-11-18T09:30:50","date_gmt":"2024-11-18T08:30:50","guid":{"rendered":"https:\/\/ufmsecretariat.org\/medecc-and-ufm-mediterranean-countries-climate-change-mitigation-and-adaptation-efforts-still-insufficient-for-liveable-futures\/"},"modified":"2024-11-18T09:59:32","modified_gmt":"2024-11-18T08:59:32","slug":"medecc-and-ufm-mediterranean-countries-climate-change-mitigation-and-adaptation-efforts-still-insufficient-for-liveable-futures","status":"publish","type":"post","link":"https:\/\/ufmsecretariat.org\/fr\/medecc-and-ufm-mediterranean-countries-climate-change-mitigation-and-adaptation-efforts-still-insufficient-for-liveable-futures\/","title":{"rendered":"MedECC et l\u2019UpM : Les efforts d\u2019att\u00e9nuation et d\u2019adaptation des pays m\u00e9diterran\u00e9ens face au changement climatique restent insuffisants pour garantir des futurs vivables"},"content":{"rendered":"<ul>\n<li><a href=\"https:\/\/www.medecc.org\/\"><strong>Le r\u00e9seau d\u2019experts m\u00e9diterran\u00e9ens sur les changements climatiques et environnementaux<\/strong><\/a><strong> (MedECC), et <\/strong><a href=\"https:\/\/ufmsecretariat.org\/\"><strong>l\u2019Union pour la M\u00e9diterran\u00e9e<\/strong><\/a><strong> (UpM) ont pr\u00e9sent\u00e9 aujourd\u2019hui, depuis la COP29 \u00e0 Bakou, les derni\u00e8res conclusions scientifiques sur les impacts du changement climatique et de la d\u00e9gradation de l\u2019environnement dans les zones c\u00f4ti\u00e8res de la r\u00e9gion, ainsi que sur le nexus Eau-\u00c9nergie-Alimentation-\u00c9cosyst\u00e8mes (WEFE).<\/strong><\/li>\n<li><strong>Un tiers de la population m\u00e9diterran\u00e9enne vit \u00e0 proximit\u00e9 imm\u00e9diate de la mer, une r\u00e9gion parmi les plus expos\u00e9es au monde aux inondations compos\u00e9es, et de plus en plus vuln\u00e9rable aux risques li\u00e9s au changement climatique et \u00e0 la d\u00e9gradation de l\u2019environnement.<\/strong><\/li>\n<li><strong>Les impacts de ce ph\u00e9nom\u00e8ne s\u2019aggraveront dans les ann\u00e9es \u00e0 venir si des mesures urgentes ne sont pas prises d\u00e8s maintenant. Atteindre les Objectifs de d\u00e9veloppement durable des Nations Unies n\u00e9cessitera des politiques transfrontali\u00e8res promouvant des solutions innovantes, y compris les \u00e9nergies renouvelables, et des changements comportementaux moins \u00e9nergivores, tels que le retour g\u00e9n\u00e9ralis\u00e9 \u00e0 la di\u00e8te m\u00e9diterran\u00e9enne.<\/strong><\/li>\n<\/ul>\n<p><strong>18 novembre 2024, COP29<\/strong>. Les impacts du changement climatique d\u2019origine humaine dans la r\u00e9gion m\u00e9diterran\u00e9e, un point chaud du r\u00e9chauffement climatique, deviennent de plus en plus visibles. Moins de trois semaines apr\u00e8s les inondations d\u00e9vastatrices ayant frapp\u00e9 la r\u00e9gion de Valence en Espagne, <a href=\"https:\/\/ufmsecretariat.org\/mediterraneanpavilion\/event\/press-conference-medecc-reports\/\" target=\"_blank\" rel=\"noopener\">MedECC et l\u2019UpM ont pr\u00e9sent\u00e9 les derni\u00e8res conclusions scientifiques<\/a> du r\u00e9seau sur les implications dangereuses du changement climatique et de la d\u00e9gradation de l\u2019environnement pour les zones c\u00f4ti\u00e8res m\u00e9diterran\u00e9ennes et le nexus WEFE.<\/p>\n<p>Les scientifiques Piero Lionello, de l\u2019Universit\u00e9 de Salento, et Mohamed Abdel Monem, consultant ind\u00e9pendant sur le changement climatique et le d\u00e9veloppement rural, ont soulign\u00e9 l\u2019urgence de mesures d\u2019adaptation et d\u2019att\u00e9nuation plus efficaces dans la r\u00e9gion, aux c\u00f4t\u00e9s de Grammenos Mastrojeni, secr\u00e9taire g\u00e9n\u00e9ral adjoint pour l\u2019Action \u00e9nerg\u00e9tique et climatique de l\u2019UpM.<\/p>\n<p><em>\u00ab La mer M\u00e9diterran\u00e9e est une source de grande fiert\u00e9 pour les 22 pays qui bordent ses c\u00f4tes, un \u00e9l\u00e9ment inextricable de leur identit\u00e9 et de leur patrimoine \u00bb,<\/em> a d\u00e9clar\u00e9 Grammenos Mastrojeni.<br \/>\n<em>\u00ab Mais il est temps d\u2019accepter que la M\u00e9diterran\u00e9e telle que nous la connaissons pourrait ne plus exister si nos efforts pour contrer le changement climatique continuent d\u2019\u00eatre insuffisants. Compte tenu de son importance cruciale, soutenir la transition verte a toujours \u00e9t\u00e9 une des grandes priorit\u00e9s de l\u2019Union pour la M\u00e9diterran\u00e9e. \u00bb<\/em><\/p>\n<p>S\u2019appuyant sur le <a href=\"https:\/\/ufmsecretariat.org\/fr\/climate\/\">Rapport d\u2019\u00e9valuation m\u00e9diterran\u00e9en (MAR1)<\/a>, le premier rapport scientifique couvrant l\u2019impact du changement climatique et la d\u00e9gradation de l\u2019environnement en M\u00e9diterran\u00e9e, les nouvelles \u00e9tudes du r\u00e9seau MedECC tirent une fois de plus la sonnette d\u2019alarme, en attirant l\u2019attention sur les risques actuels et projet\u00e9s tout en proposant des actions pour en minimiser les cons\u00e9quences.<\/p>\n<p>Si les tendances actuelles se poursuivent, jusqu\u2019\u00e0 20 millions de personnes pourraient \u00eatre d\u00e9plac\u00e9es de fa\u00e7on permanente en raison de l\u2019\u00e9l\u00e9vation du niveau de la mer d\u2019ici 2100. Les vagues de chaleur marine, dont la fr\u00e9quence et la dur\u00e9e ont respectivement augment\u00e9 de 40 % et 15 % au cours des deux derni\u00e8res d\u00e9cennies, associ\u00e9es \u00e0 la d\u00e9gradation environnementale dans une des r\u00e9gions les plus pollu\u00e9es par les plastiques au monde, engendrent une vari\u00e9t\u00e9 d\u2019effets \u00e9cologiques et socio-\u00e9conomiques pr\u00e9occupants. La r\u00e9gion fait \u00e9galement face \u00e0 des pics de demande en eau importants durant l\u2019\u00e9t\u00e9, une tendance qui devrait s\u2019intensifier dans les ann\u00e9es \u00e0 venir en raison du changement climatique, de nos pratiques agricoles, ainsi que de l\u2019augmentation de la population et du tourisme dans les zones c\u00f4ti\u00e8res.<\/p>\n<p>Un \u00e9ventail d\u2019instruments juridiques, politiques et \u00e9conomiques est disponible pour promouvoir une \u00e9conomie bleue durable et d\u00e9coupler la consommation d\u2019\u00e9nergie de la croissance \u00e9conomique. \u00c9tant donn\u00e9 que les effets du changement climatique amplifient les probl\u00e8mes socio-\u00e9conomiques et environnementaux existants, les voies d\u2019action les plus r\u00e9ussies impliqueront des solutions technologiques, soci\u00e9tales et bas\u00e9es sur les \u00e9cosyst\u00e8mes, en prenant en compte les quatre \u00e9l\u00e9ments interconnect\u00e9s du nexus WEFE.<\/p>\n<p><strong>Consultez le r\u00e9sum\u00e9 de presse des principales conclusions <\/strong><a href=\"https:\/\/drive.google.com\/drive\/folders\/15mXKPWTwddv4kyLVs38d7-xcNCam3UjD?usp=sharing\"><strong>ici<\/strong><\/a><strong>.<\/strong><\/p>\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1505467329702 \">\n<div id=\"ct_5920aez20fum6l2czjwv\" class=\"wpb_wrapper\">\n<p><strong>Check:\u00a0<a href=\"https:\/\/www.medecc.org\/medecc-reports\/med-coastal-risks\/\">Special Report on Climate and Environmental Coastal Risks in the Mediterranean<\/a><\/strong><\/p>\n<p><strong>Check:\u00a0<a href=\"https:\/\/www.medecc.org\/medecc-reports\/climate-wefe-nexus\/\">Special Report Interlinking climate change with the Water \u2013 Energy \u2013 Food \u2013 Ecosystems (WEFE) nexus in the Mediterranean Basin<\/a><\/strong><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le r\u00e9seau d\u2019experts m\u00e9diterran\u00e9ens sur les changements climatiques et environnementaux (MedECC), et l\u2019Union pour la M\u00e9diterran\u00e9e (UpM) ont pr\u00e9sent\u00e9 aujourd\u2019hui, depuis la COP29 \u00e0 Bakou, les derni\u00e8res conclusions scientifiques sur les impacts du changement climatique et de la d\u00e9gradation de l\u2019environnement dans les zones c\u00f4ti\u00e8res de la r\u00e9gion, ainsi que sur le nexus Eau-\u00c9nergie-Alimentation-\u00c9cosyst\u00e8mes (WEFE).<br \/><a href=\"https:\/\/ufmsecretariat.org\/fr\/medecc-and-ufm-mediterranean-countries-climate-change-mitigation-and-adaptation-efforts-still-insufficient-for-liveable-futures\/\" class=\"more\">Lire la suite<\/a><\/p>\n","protected":false},"author":38,"featured_media":186620,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92,85],"tags":[],"priority-area":[201,198],"class_list":["post-185771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-actualites-phares","priority-area-water-environment-fr","priority-area-energy-climate-action-fr"],"_links":{"self":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/185771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/comments?post=185771"}],"version-history":[{"count":3,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/185771\/revisions"}],"predecessor-version":[{"id":186624,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/185771\/revisions\/186624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/media\/186620"}],"wp:attachment":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/media?parent=185771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/categories?post=185771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/tags?post=185771"},{"taxonomy":"priority-area","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/priority-area?post=185771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}