

{"id":194334,"date":"2024-11-25T13:37:14","date_gmt":"2024-11-25T12:37:14","guid":{"rendered":"https:\/\/ufmsecretariat.org\/?p=194334"},"modified":"2024-12-18T12:42:48","modified_gmt":"2024-12-18T11:42:48","slug":"dialogos-para-la-seguridad","status":"publish","type":"post","link":"https:\/\/ufmsecretariat.org\/fr\/dialogos-para-la-seguridad\/","title":{"rendered":"L&#8217;UpM s\u2019engage \u00e0 soutenir une \u201cvision centr\u00e9e sur la paix\u201d au Moyen-Orient"},"content":{"rendered":"<p><strong>Barcelone, 25 novembre 2024.<\/strong> Le secr\u00e9taire g\u00e9n\u00e9ral de l\u2019UpM, Nasser Kamel, a particip\u00e9 \u00e0 Madrid \u00e0 l\u2019\u00e9v\u00e9nement \u00ab <em>Di\u00e1logos para la Seguridad<\/em> \u00bb (Dialogues pour la s\u00e9curit\u00e9) organis\u00e9 par le journal <em>El Pa\u00eds<\/em>.<\/p>\n<p>L\u2019\u00e9v\u00e9nement a r\u00e9uni de nombreux intervenants de renom pour d\u00e9battre des d\u00e9fis g\u00e9opolitiques et s\u00e9curitaires complexes auxquels sont confront\u00e9s l\u2019Europe et la r\u00e9gion m\u00e9diterran\u00e9enne : de la guerre en Ukraine et du conflit isra\u00e9lo-palestinien, \u00e0 la migration irr\u00e9guli\u00e8re, la radicalisation et la d\u00e9sinformation.<\/p>\n<p>Lors d\u2019une session d\u00e9di\u00e9e \u00e0 la situation en M\u00e9diterran\u00e9e intitul\u00e9e \u00ab Un regard sur la M\u00e9diterran\u00e9e \u00bb, le secr\u00e9taire g\u00e9n\u00e9ral de l\u2019UpM a partag\u00e9 son analyse de l\u2019impact des crises g\u00e9opolitiques en cours au Moyen-Orient sur la stabilit\u00e9 et la prosp\u00e9rit\u00e9 dans la r\u00e9gion m\u00e9diterran\u00e9enne et au-del\u00e0.<\/p>\n<p>\u00ab <em>Au cours des vingt derni\u00e8res ann\u00e9es, la M\u00e9diterran\u00e9e a subi une grande instabilit\u00e9, aggrav\u00e9e par une s\u00e9rie d\u2019\u00e9v\u00e9nements. Dans ce contexte, le conflit isra\u00e9lo-palestinien prolong\u00e9 constitue naturellement l\u2019\u00e9picentre des tensions pour toute la r\u00e9gion et au-del\u00e0<\/em> \u00bb, a d\u00e9clar\u00e9 M. Kamel.<\/p>\n<p>Il a ajout\u00e9 que la d\u00e9vastation, les pertes humaines et la catastrophe humanitaire croissante \u00e0 Gaza, ainsi que la polarisation aigu\u00eb qu\u2019elle engendre \u00e0 travers le monde, n\u00e9cessitent une attention particuli\u00e8re, soulignant aussi\u00a0les r\u00e9percussions de ce conflit non seulement sur la s\u00e9curit\u00e9 et le paysage humain et politique en M\u00e9diterran\u00e9e, mais \u00e9galement sur le cadre normatif qui guide la communaut\u00e9 internationale.<\/p>\n<p>M. Kamel a insist\u00e9 sur le fait que la seule vision viable pour la r\u00e9gion repose sur ce qu\u2019il appelle \u00ab une vision centr\u00e9e sur la paix \u00bb, qui cherche \u00e0 instaurer une r\u00e9conciliation et une coexistence entre les deux parties, \u00e0 travers une paix durable fond\u00e9e exclusivement sur la solution \u00e0 deux \u00c9tats. Il a confirm\u00e9 la volont\u00e9 de l\u2019UpM de soutenir cette vision, en mettant en avant l\u2019unicit\u00e9 de l\u2019organisation, qui regroupe Isra\u00ebl et la Palestine en tant que membres \u00e0 \u00e9galit\u00e9 de droits et de statut.<\/p>\n<p>\u00ab <em>Les \u00c9tats membres de l\u2019UpM ne doivent pas abandonner les efforts en vue d\u2019un dialogue constructif entre l\u2019Europe et ses voisins du sud de la M\u00e9diterran\u00e9e. L\u2019\u00e9chec de cette d\u00e9marche, tout comme un conflit prolong\u00e9 dans la r\u00e9gion, aurait des r\u00e9percussions g\u00e9opolitiques et s\u00e9curitaires consid\u00e9rables.<\/em> \u00bb<\/p>\n<p>Le secr\u00e9taire g\u00e9n\u00e9ral de l\u2019UpM a n\u00e9anmoins conclu sur une note positive, d\u00e9clarant : \u00ab <em>Malgr\u00e9 la perception pessimiste de la M\u00e9diterran\u00e9e comme une zone marqu\u00e9e par les tensions, notre r\u00e9gion est un espace de connexions remarquables et de r\u00e9silience. Elle relie continents et cultures, offrant un vaste potentiel de prosp\u00e9rit\u00e9 qui transcende les fronti\u00e8res<\/em>. \u00bb<\/p>\n<p>En marge de la r\u00e9union, le secr\u00e9taire g\u00e9n\u00e9ral a rencontr\u00e9 le ministre des Affaires \u00e9trang\u00e8res, de l\u2019Union europ\u00e9enne et de la Coop\u00e9ration d\u2019Espagne, S.E. M. Jos\u00e9 Manuel Albares. Ils ont discut\u00e9 des prochaines \u00e9tapes de la r\u00e9forme de l\u2019UpM en vue du 30\u1d49 anniversaire du Processus de Barcelone et du 10\u1d49 Forum r\u00e9gional de l\u2019UpM l\u2019ann\u00e9e prochaine, ainsi que de son alignement avec le futur Pacte pour la M\u00e9diterran\u00e9e de l\u2019Union europ\u00e9enne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Barcelone, 25 novembre 2024. Le secr\u00e9taire g\u00e9n\u00e9ral de l\u2019UpM, Nasser Kamel, a particip\u00e9 \u00e0 Madrid \u00e0 l\u2019\u00e9v\u00e9nement \u00ab Di\u00e1logos para la Seguridad \u00bb (Dialogues pour la s\u00e9curit\u00e9) organis\u00e9 par le journal El Pa\u00eds. L\u2019\u00e9v\u00e9nement a r\u00e9uni de nombreux intervenants de renom pour d\u00e9battre des d\u00e9fis g\u00e9opolitiques et s\u00e9curitaires complexes auxquels sont confront\u00e9s l\u2019Europe et la<br \/><a href=\"https:\/\/ufmsecretariat.org\/fr\/dialogos-para-la-seguridad\/\" class=\"more\">Lire la suite<\/a><\/p>\n","protected":false},"author":38,"featured_media":194331,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92,85],"tags":[],"priority-area":[12782],"class_list":["post-194334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-actualites-phares","priority-area-activity-of-the-secretary-general-fr"],"_links":{"self":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/194334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/comments?post=194334"}],"version-history":[{"count":3,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/194334\/revisions"}],"predecessor-version":[{"id":201468,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/posts\/194334\/revisions\/201468"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/media\/194331"}],"wp:attachment":[{"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/media?parent=194334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/categories?post=194334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/tags?post=194334"},{"taxonomy":"priority-area","embeddable":true,"href":"https:\/\/ufmsecretariat.org\/fr\/wp-json\/wp\/v2\/priority-area?post=194334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}